{"id":57,"date":"2025-08-10T15:35:46","date_gmt":"2025-08-10T15:35:46","guid":{"rendered":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/?p=57"},"modified":"2025-08-10T15:35:46","modified_gmt":"2025-08-10T15:35:46","slug":"autoportrait","status":"publish","type":"post","link":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/2025\/08\/10\/autoportrait\/","title":{"rendered":"Autoportrait"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ma fonction n\u2019est pas photographe. Je m\u2019appelle Daniel. Mon appareil le plus r\u00e9cent est un Nikon D7000. Un objectif 18-105. Ce n\u2019est qu\u2019une passion. Bien s\u00fbr quand on me le demande je peux r\u00e9aliser des clich\u00e9s de l\u2019enfant qui vient de na\u00eetre, des jeunes mari\u00e9s \u00ab&nbsp;Daniel, bien entendu tu es invit\u00e9 mais si tu pouvais faire quelques photos, rien que pour nous\u2026&nbsp;\u00bb. Je ne refuse que rarement bonne ch\u00e8re et compagnie. J\u2019y glane toujours quelques images. Et quelques connivences dont certaines sont un tremplin vers d\u2019autres sauteries.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mich\u00e8le, m\u2019invitant au mariage de sa fille cadette, pour les m\u00eames raisons que je viens d\u2019exposer, me dit en me prenant la main pour sceller notre accord \u00ab&nbsp;Daniel, tu es le photographe le plus gourmand et opportuniste que je connaisse&nbsp;\u00bb.&nbsp;&nbsp;Elle a plus caress\u00e9 que serr\u00e9 la main&nbsp;&nbsp;que je laissais n\u00e9gligemment \u00e0 sa port\u00e9e. L\u2019affaire fut ainsi consid\u00e9r\u00e9e comme conclue et je passerai sous silence ce qui suivit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mich\u00e8le et Fran\u00e7ois sont les parents et je les ai longtemps fr\u00e9quent\u00e9s en couple avec enfant. La petite s\u2019appelle Ariel. Je la connais depuis son plus jeune \u00e2ge et je dois t\u2019avouer que j\u2019ai longtemps cru qu\u2019il s\u2019agissait d\u2019un petit gar\u00e7on, puis d\u2019un adolescent eff\u00e9min\u00e9. Mich\u00e8le m\u2019a annonc\u00e9 son futur mariage. Fran\u00e7ois, non, je ne le vois plus. Il a d\u00e9m\u00e9nag\u00e9. Oui, il sera pr\u00e9sent, c\u2019est quand m\u00eame sa fille.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019aurai d\u00fb m\u2019int\u00e9resser aux oiseaux. Rien qu\u2019en ville de ma fen\u00eatre j\u2019en vois des tas, tous diff\u00e9rents, pr\u00eats \u00e0 fondre sur une proie, un ennemi ou quelque miette. Mon mat\u00e9riel me permettrait des clich\u00e9s r\u00e9ussis de jour comme de nuit. Ou aux chats, aux chiens, aux rats\u2026 Seulement tous ces volatiles, mammif\u00e8res domestiques ou non ne m\u2019ont jamais convi\u00e9 \u00e0 de quelconques agapes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le mois dernier j\u2019ai assist\u00e9 aux obs\u00e8ques de Marcel. C\u2019est un ancien chef de service. Tous les membres du bureau se sont cotis\u00e9s pour une couronne orn\u00e9e d\u2019un ruban vantant ses m\u00e9rites. Sa famille, femme, enfants et associ\u00e9s, affichaient des mines tristes durant la c\u00e9r\u00e9monie. Quelques-uns se sont exprim\u00e9s en louanges et regrets. Les photos de familles alternaient aux photos de la vie de notre bureau au fil de ses ann\u00e9es de services. Non, je ne suis sur aucune, c\u2019est moi qui les ai faites. Je suis l\u2019observateur, le t\u00e9moin\u2026 Les proches sont venus me taper sur l\u2019\u00e9paule et me remercier du r\u00e9alisme de mes clich\u00e9s, du s\u00e9rieux de mon t\u00e9moignage, d\u2019avoir \u00e9t\u00e9 son ami.\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ami de Marcel ? Non je ne l\u2019ai jamais \u00e9t\u00e9 et quand il a quitt\u00e9 son poste avec les remerciements de la direction je me suis empress\u00e9 d\u2019occuper son bureau acceptant avec un bel opportunisme les ronds de jambes et f\u00e9licitations de mes inf\u00e9rieurs dans l\u2019organigramme.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mich\u00e8le aurait-elle raison ? Je suis chef de service mais ce poste je le m\u00e9rite non ? Je garde dans mon tiroir le Nikon et sa batterie de rechange. Il ne faudrait pas que je sois \u00e0 court d\u2019\u00e9nergie. La seule diff\u00e9rence dans ma routine est que je ne le sors plus \u00e0 l\u2019heure du d\u00e9jeuner. J\u2019ai surpris le stagiaire a faire des photos avec sont t\u00e9l\u00e9phone portable, un truc avec trois objectif, certainement pas celui fourni par le bureau. Maintenant quand je le croise dans les couloirs ou \u00e0 la cantine, j\u2019ai toujours avec moi un livre, un journal, un dossier\u2026 Je ne sais jamais s\u2019il m\u2019espionne, donc je suis pr\u00eat \u00e0 me rendre invisible. J\u2019ai choisi mon camp, c\u2019est moi qui observe, c\u2019est moi qui choisis, c\u2019est moi qui capture. J\u2019ai l\u2019instinct d\u2019un chasseur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec Mich\u00e8le nous avons ouvert des albums qui n\u2019avaient plus \u00e9t\u00e9 consult\u00e9s depuis au moins quinze ans. Le bapt\u00eame d\u2019Ariel. Quelques invit\u00e9s pris au hasard dit-elle. Je r\u00e9torque \u00ab&nbsp;je suis photographe, il ne peut y avoir de hasard&nbsp;\u00bb. Je lui montre ce couple, la jeune femme rousse et l\u2019homme sans importance qui lui donne le bras. Lui on a oubli\u00e9 jusqu\u2019\u00e0 son nom mais elle je me souviens tr\u00e8s bien, elle se nomme Annie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Tu l\u2019as revue ? me demande-t-elle avec un air faussement choqu\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Quelques fois, disons heu plusieurs\u2026L\u2019album des vacances en Corse.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Non, ne l\u2019ouvrons pas aujourd\u2019hui, c\u2019est l\u2019\u00e9t\u00e9 o\u00f9 Fran\u00e7ois, elle ne termine pas sa phrase. J\u2019aurais d\u00fb m\u2019en d\u00e9barrasser. C\u2019est Ariel qui m\u2019en a emp\u00each\u00e9 car ce sont les derni\u00e8res photos de ses parents ensemble\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Donne-le lui pour son mariage, r\u00e9am\u00e9nage, faisons un tri. Pour avoir \u00e9t\u00e9 le photographe et le t\u00e9moin je peux mettre un nom sur chacun des protagonistes Si on consid\u00e8re ensemble les faits sous un autre angle je peux r\u00e9arranger l\u2019histoire.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai parfois des regrets. Mes amis me r\u00e9clament mais ce qu\u2019ils veulent vraiment ce sont des images d\u2019eux-m\u00eame. Des images positives, des simulacres de jours et de gens heureux. Des anecdotes qu\u2019ils peuvent inventer, des vies recr\u00e9\u00e9es pour une occasion ou une autre, des images lisses \u00e0 transmettre, \u00e0 laisser \u00e0 la post\u00e9rit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les gens disent de moi que je suis un vieux gar\u00e7on parce que je vis seul dans mon petit appartement. J\u2019ai une chambre confortable. Un labo photo \u00e0 l\u2019ancienne avec cette l\u00e9g\u00e8re odeur vinaigr\u00e9e qui flotte derri\u00e8re la lumi\u00e8re rouge. Un salon un peu d\u00e9suet d\u2019\u00eatre sous-occup\u00e9. Une cuisine o\u00f9 je mange seul le plus souvent. Un grand placard dont les \u00e9tag\u00e8res sont occup\u00e9es de bo\u00eetes num\u00e9rot\u00e9es dat\u00e9es. Elles contiennent les photos que je n\u2019ai pas montr\u00e9es. Ces photos peupl\u00e9es de personnages qui ne sourient pas, qui se tiennent mal, qui mijotent des actions que je ne veux pas conna\u00eetre. Que je n\u2019ai pas eu le courage de reconna\u00eetre. Une histoire du monde se cache sous les couvercles, une narration que j\u2019aurais du mal \u00e0 reconditionner. Puis il y a cette bo\u00eete rouge qui cache les auto-portrait dans la salle de bain. Moi, moi, et moi\u2026 La m\u00eame pose, l\u2019\u00e9clairage identique, le miroir quelques fois brumeux, moi-m\u00eame.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma fonction n\u2019est pas photographe. Je m\u2019appelle Daniel. Mon appareil le plus r\u00e9cent est un Nikon D7000. Un objectif 18-105.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-57","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":1,"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"predecessor-version":[{"id":58,"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/posts\/57\/revisions\/58"}],"wp:attachment":[{"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/pcdrnhf.cluster021.hosting.ovh.net\/index.php\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}